{"id":2952,"date":"2010-01-28T13:49:25","date_gmt":"2010-01-28T12:49:25","guid":{"rendered":"http:\/\/dev.hsp-kanzlei.com\/?p=2952"},"modified":"2024-04-19T10:59:29","modified_gmt":"2024-04-19T08:59:29","slug":"haustuergeschaeft-zurechnung-auf-bank-ii","status":"publish","type":"post","link":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/","title":{"rendered":"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank&nbsp;II"},"content":{"rendered":"<p>Im Anschluss an seine bereits in der Vergangenheit bereits verbraucherfreundliche Entscheidung vom 03.05.2005 (II ZR 319\/04) erging eine weitere Entscheidung des II. Senats des Bundesgerichtshofs zur Problematik des Haust\u00fcrwiderrufsgesetzes (HWiG). Im Anschluss an die eindeutige Rechtsprechung des Europ\u00e4ischen Gerichtshofs bestimmt das Gericht am 12.12.2005 (II ZR 327\/04) nunmehr im Leitsatz folgendes:<\/p>\n<p><i>Nach richtlinienkonformer Auslegung des \u00a7 1 HWiG muss ein Vertragspartner, der nicht selbst die Vertragsverhandlungen f\u00fchrt, von der in der Person des Verhandlungsf\u00fchrers bestehenden Haust\u00fcrsituation keine Kenntnis haben. Ebenso wenig kommt es darauf an, ob den Vertragspartner an seiner Unkenntnis ein Verschulden trifft. Vielmehr ist \u00a7 1 HWiG immer dann anwendbar, wenn objektiv eine Haust\u00fcrsituation bestanden hat.<\/i><\/p>\n<p>Aufgrund dieser Entscheidung kommt es nun nicht mehr auf ein subjektives Wissenselement der Bank&nbsp;an.<\/p>\n<p>Das Haust\u00fcrwiderrufsgesetz gilt unbedingt und ausnahmslos in jedem Fall, in welchem eine Haust\u00fcrsituation vorgelegen hat. Dies ist der Fall, bei Abschluss eines Gespr\u00e4chs<\/p>\n<ol>\n<li>in den eigenen Wohnr\u00e4umlichkeiten,<\/li>\n<li>nach Ansprechen am Arbeitsplatz oder<\/li>\n<li>nach Ansprechen auf der Stra\u00dfe.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>In allen F\u00e4llen ist ein Widerruf auch noch nach l\u00e4ngeren Zeitr\u00e4umen m\u00f6glich.<\/p>\n<p>Zusammengefasst hat sich mit dieser Entscheidung die Rechtsprechung sowohl des II. Senats wie auch des - zun\u00e4chst bankenfreundlich entscheidenden - XI. Zivilsenats des Bundesgerichtshofs endg\u00fcltig, im Sinne der anlegerfreundlichen europarechtlichen Rechtsprechung, gewandelt.<\/p>\n<p>F\u00fcr gesch\u00e4digte Anleger bedeutet diese Rechtsprechung die M\u00f6glichkeit, auch aus teilweise schwierigen rechtlichen Kapitalanlagekonzepten, auszusteigen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Anschluss an seine bereits in der Vergangenheit bereits verbraucherfreundliche Entscheidung vom 03.05.2005 (II ZR 319\/04) erging eine weitere Entscheidung des II. Senats des Bundesgerichtshofs zur Problematik des Haust\u00fcrwiderrufsgesetzes (HWiG). Im Anschluss an die eindeutige Rechtsprechung des Europ\u00e4ischen Gerichtshofs bestimmt das Gericht am 12.12.2005 (II ZR 327\/04) nunmehr im Leitsatz folgendes: Nach richtlinienkonformer Auslegung des&nbsp;[\u2026]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[69,1],"tags":[],"class_list":["post-2952","post","type-post","status-publish","format-standard","hentry","category-kapitalanlagerecht","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank II | HSP Steuerberater | Rechtsanw\u00e4lte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank II | HSP Steuerberater | Rechtsanw\u00e4lte\" \/>\n<meta property=\"og:description\" content=\"Im Anschluss an seine bereits in der Vergangenheit bereits verbraucherfreundliche Entscheidung vom 03.05.2005 (II ZR 319\/04) erging eine weitere Entscheidung des II. Senats des Bundesgerichtshofs zur Problematik des Haust\u00fcrwiderrufsgesetzes (HWiG). Im Anschluss an die eindeutige Rechtsprechung des Europ\u00e4ischen Gerichtshofs bestimmt das Gericht am 12.12.2005 (II ZR 327\/04) nunmehr im Leitsatz folgendes: Nach richtlinienkonformer Auslegung des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"HSP Steuerberater | Rechtsanw\u00e4lte\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-28T12:49:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-19T08:59:29+00:00\" \/>\n<meta name=\"author\" content=\"HSP-Kanzlei\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"HSP-Kanzlei\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/haustuergeschaeft-zurechnung-auf-bank-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/haustuergeschaeft-zurechnung-auf-bank-ii\\\/\"},\"author\":{\"name\":\"HSP-Kanzlei\",\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#\\\/schema\\\/person\\\/727e39255c7bfc540c3f3be47952ce75\"},\"headline\":\"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank&nbsp;II\",\"datePublished\":\"2010-01-28T12:49:25+00:00\",\"dateModified\":\"2024-04-19T08:59:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/haustuergeschaeft-zurechnung-auf-bank-ii\\\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#organization\"},\"articleSection\":[\"Kapitalanlagerecht\",\"Unkategorisiert\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/haustuergeschaeft-zurechnung-auf-bank-ii\\\/\",\"url\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/haustuergeschaeft-zurechnung-auf-bank-ii\\\/\",\"name\":\"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank II | HSP Steuerberater | Rechtsanw\u00e4lte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#website\"},\"datePublished\":\"2010-01-28T12:49:25+00:00\",\"dateModified\":\"2024-04-19T08:59:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/haustuergeschaeft-zurechnung-auf-bank-ii\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/haustuergeschaeft-zurechnung-auf-bank-ii\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/haustuergeschaeft-zurechnung-auf-bank-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/homepage-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/\",\"name\":\"HSP Steuerberater | Rechtsanw\u00e4lte\",\"description\":\"Steuerberater &amp; Rechtsanw\u00e4lte\",\"publisher\":{\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#organization\",\"name\":\"HSP Steuerberater | Rechtsanw\u00e4lte\",\"url\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hsp-kanzlei.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HSP-Logo.svg\",\"contentUrl\":\"https:\\\/\\\/hsp-kanzlei.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HSP-Logo.svg\",\"width\":141,\"height\":126.6,\"caption\":\"HSP Steuerberater | Rechtsanw\u00e4lte\"},\"image\":{\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/#\\\/schema\\\/person\\\/727e39255c7bfc540c3f3be47952ce75\",\"name\":\"HSP-Kanzlei\",\"sameAs\":[\"https:\\\/\\\/hsp-kanzlei.com\"],\"url\":\"https:\\\/\\\/hsp-kanzlei.com\\\/en\\\/aktuelles\\\/author\\\/hsp-kanzlei\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank II | HSP Steuerberater | Rechtsanw\u00e4lte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/","og_locale":"en_US","og_type":"article","og_title":"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank II | HSP Steuerberater | Rechtsanw\u00e4lte","og_description":"Im Anschluss an seine bereits in der Vergangenheit bereits verbraucherfreundliche Entscheidung vom 03.05.2005 (II ZR 319\/04) erging eine weitere Entscheidung des II. Senats des Bundesgerichtshofs zur Problematik des Haust\u00fcrwiderrufsgesetzes (HWiG). Im Anschluss an die eindeutige Rechtsprechung des Europ\u00e4ischen Gerichtshofs bestimmt das Gericht am 12.12.2005 (II ZR 327\/04) nunmehr im Leitsatz folgendes: Nach richtlinienkonformer Auslegung des [&hellip;]","og_url":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/","og_site_name":"HSP Steuerberater | Rechtsanw\u00e4lte","article_published_time":"2010-01-28T12:49:25+00:00","article_modified_time":"2024-04-19T08:59:29+00:00","author":"HSP-Kanzlei","twitter_card":"summary_large_image","twitter_misc":{"Written by":"HSP-Kanzlei","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/#article","isPartOf":{"@id":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/"},"author":{"name":"HSP-Kanzlei","@id":"https:\/\/hsp-kanzlei.com\/en\/#\/schema\/person\/727e39255c7bfc540c3f3be47952ce75"},"headline":"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank&nbsp;II","datePublished":"2010-01-28T12:49:25+00:00","dateModified":"2024-04-19T08:59:29+00:00","mainEntityOfPage":{"@id":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/"},"wordCount":239,"publisher":{"@id":"https:\/\/hsp-kanzlei.com\/en\/#organization"},"articleSection":["Kapitalanlagerecht","Unkategorisiert"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/","url":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/","name":"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank II | HSP Steuerberater | Rechtsanw\u00e4lte","isPartOf":{"@id":"https:\/\/hsp-kanzlei.com\/en\/#website"},"datePublished":"2010-01-28T12:49:25+00:00","dateModified":"2024-04-19T08:59:29+00:00","breadcrumb":{"@id":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/haustuergeschaeft-zurechnung-auf-bank-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hsp-kanzlei.com\/en\/homepage-2\/"},{"@type":"ListItem","position":2,"name":"Haust\u00fcrgesch\u00e4ft: Zurechnung auf Bank II"}]},{"@type":"WebSite","@id":"https:\/\/hsp-kanzlei.com\/en\/#website","url":"https:\/\/hsp-kanzlei.com\/en\/","name":"HSP Steuerberater | Rechtsanw\u00e4lte","description":"Steuerberater &amp; Rechtsanw\u00e4lte","publisher":{"@id":"https:\/\/hsp-kanzlei.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hsp-kanzlei.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hsp-kanzlei.com\/en\/#organization","name":"HSP Steuerberater | Rechtsanw\u00e4lte","url":"https:\/\/hsp-kanzlei.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hsp-kanzlei.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hsp-kanzlei.com\/wp-content\/uploads\/2021\/11\/HSP-Logo.svg","contentUrl":"https:\/\/hsp-kanzlei.com\/wp-content\/uploads\/2021\/11\/HSP-Logo.svg","width":141,"height":126.6,"caption":"HSP Steuerberater | Rechtsanw\u00e4lte"},"image":{"@id":"https:\/\/hsp-kanzlei.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hsp-kanzlei.com\/en\/#\/schema\/person\/727e39255c7bfc540c3f3be47952ce75","name":"HSP-Kanzlei","sameAs":["https:\/\/hsp-kanzlei.com"],"url":"https:\/\/hsp-kanzlei.com\/en\/aktuelles\/author\/hsp-kanzlei\/"}]}},"_links":{"self":[{"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/posts\/2952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/comments?post=2952"}],"version-history":[{"count":1,"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/posts\/2952\/revisions"}],"predecessor-version":[{"id":8010,"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/posts\/2952\/revisions\/8010"}],"wp:attachment":[{"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/media?parent=2952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/categories?post=2952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hsp-kanzlei.com\/en\/wp-json\/wp\/v2\/tags?post=2952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}